{"id":2742,"date":"2023-04-17T18:38:59","date_gmt":"2023-04-17T21:38:59","guid":{"rendered":"https:\/\/modocooperativo.uy\/?p=2742"},"modified":"2023-04-18T11:39:29","modified_gmt":"2023-04-18T14:39:29","slug":"cooperativas-de-consumo-analizaron-situacion-del-sector-y-trabajan-en-la-concientizacion","status":"publish","type":"post","link":"https:\/\/modocooperativo.uy\/index.php\/2023\/04\/17\/cooperativas-de-consumo-analizaron-situacion-del-sector-y-trabajan-en-la-concientizacion\/","title":{"rendered":"Cooperativas de Consumo analizaron situaci\u00f3n del sector y trabajan en la concientizaci\u00f3n"},"content":{"rendered":"<p>La sede del Centro Cooperativista Uruguayo (CCU) fue escenario este s\u00e1bado del denominado Encuentro de J\u00f3venes de Cooperativas de Consumo, evento destinado a la puesta al d\u00eda, concientizaci\u00f3n y marcar un necesario recambio generacional en este sector del cooperativismo, seg\u00fan se\u00f1alan sus organizadores.<\/p>\n<p>Cont\u00f3 con la convocatoria de la Federaci\u00f3n Uruguaya de Cooperativas de Consumo (FUCC), apuntando a estos objetivos y a potenciar esta herramienta cooperativa, adem\u00e1s de promover el intercambio y la capacitaci\u00f3n en los j\u00f3venes, incluy\u00e9ndolos en la vida institucional de la federaci\u00f3n, as\u00ed como promover \u00e1mbitos de participaci\u00f3n para que funcionarios, socios y dirigentes de la cooperativa puedan formular propuestas que tiendan a desarrollar el sector, de acuerdo a lo indicado a EL TELEGRAFO por dirigentes de la FUCC.<\/p>\n<p>El encuentro, en el que participaron m\u00e1s de una veintena de j\u00f3venes, incluy\u00f3 talleres sobre la denominada econom\u00eda verde, en el marco del proyecto Movimiento Cooperativo por un Uruguay Sostenible, cont\u00e1ndose con el apoyo de la Uni\u00f3n Europea para desarrollar esta propuesta.<\/p>\n<p>De acuerdo a lo indicado a nuestro medio period\u00edstico por Mar\u00eda de los \u00c1ngeles Dati, de la FUCC, en el Uruguay funcionan trece cooperativas de consumo, de las cuales once son de Montevideo, una de Paysand\u00fa y otra de Salto.<\/p>\n<p>Se cont\u00f3 con el aporte de los dirigentes y participantes en el evento para discutir y avanzar en temas de producci\u00f3n sostenible, econom\u00eda circular, producci\u00f3n amigable con el medio ambiente, y consumo responsable, adem\u00e1s de recorrerse luego barrios cooperativos de Paysand\u00fa con integrantes de Coperpay, Fucvam y Fecovi, as\u00ed como una visita a la cooperativa sanducera Coperpay.<\/p>\n<p>Dati, secretaria de la Federaci\u00f3n Uruguaya de Cooperativas de Consumo, indic\u00f3 a nuestro medio period\u00edstico que \u201cmi cooperativa de base es la Cooperativa de la Salud P\u00fablica, (Cosap), y soy delegada de la cooperativa en Cudecoop (Confederaci\u00f3n de Entidades Cooperativas Uruguayas).<\/p>\n<p>Sobre el encuentro reflexion\u00f3 que \u201cestamos en un marco de un proyecto con la uni\u00f3n Europea, donde no solamente participan las cooperativas de consumo, sino tambi\u00e9n las Cooperativas Agrarias Federadas, la Comisi\u00f3n Nacional de Fomento Rural, el Centro Cooperativista Uruguayo, y la Federaci\u00f3n Uruguaya de Trabajo y Producci\u00f3n\u201d.<\/p>\n<p>Precis\u00f3 que a nivel nacional, \u201ctenemos a Coperpay en Paysand\u00fa, Cosalto en el departamento de Salto, que son las dos en el Interior, en tanto en Montevideo contamos con once cooperativas de consumo. Si bien el avance del mundo ha tra\u00eddo grandes superficies a nuestros departamentos y a nivel nacional, nos ha reducido la venta de los bienes y servicios que tenemos las cooperativas de consumo en este caso, pero tambi\u00e9n han habido reglamentaciones, decretos de ley, que nos han perjudicado e incluso actualmente nos siguen perjudicando, adem\u00e1s de que actualmente hay una nueva reglamentaci\u00f3n que se quiere imponer sobre deudores que afecta no solamente al cooperativismo de consumo, sino tambi\u00e9n a las cooperativas de ahorro y cr\u00e9dito. Siempre estamos enfrentando alguna situaci\u00f3n de este tipo, que es a veces por desconocimiento, por tratar igual a lo que es distinto, porque las cooperativas somos distintas a las financieras, a los bancos, y a las grandes superficies de supermercados\u201d.<\/p>\n<p>Identidades<br \/>\n\u201cNosotros lo que tenemos es una masa societaria que viene de la ra\u00edz de nuestras cooperativas, las identidades. Cuando hablo de identidades me refiero a que, por ejemplo, mi cooperativa de salud p\u00fablica fue creada por los funcionarios de la salud, las cooperativas de la Corte Electoral exactamente lo mismo, vienen de funcionarios de esos lugares, como as\u00ed tambi\u00e9n de otros casos, por ejemplo las cooperativas municipales\u201d, explic\u00f3 la entrevistada.<\/p>\n<p>\u201cTodos precisamente hemos sufrido a veces un entorpecimiento en nuestro adelanto por esa raz\u00f3n\u201d, sostuvo.<\/p>\n<p>Destac\u00f3 que \u201cen este encuentro de Paysand\u00fa la motivaci\u00f3n principal ha sido concientizar, porque de esto se trata precisamente la econom\u00eda verde, como denominamos a nuestro proyecto con la Uni\u00f3n Europea. Se trata de concientizar a los propios cooperativistas para que esto derrame en la poblaci\u00f3n en general. Es fundamental, tenemos un llamado mundial sobre el medio ambiente y las cooperativas tenemos dentro de nuestros principios y valores justamente, eso, tratar de que el medio ambiente no sea perjudicado, porque en realidad a esta altura ya est\u00e1 muy perjudicado, hay que hacer algo. Seamos responsables dentro de nuestras organizaciones cooperativas para que esto funcione de otra manera. Las agrarias lo est\u00e1n tomando, como asimismo las propias cooperativas de consumo, las de trabajo, que tienen mucho que ver con el ambiente tambi\u00e9n y por eso se nucle\u00f3 en ese proyecto estas caracter\u00edsticas tan significativas\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>fuente: <a href=\"http:\/\/www.eltelegrafo.com\" target=\"_blank\" rel=\"noopener\">www.eltelegrafo.com<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sede del Centro Cooperativista Uruguayo (CCU) fue escenario este s\u00e1bado del denominado Encuentro de J\u00f3venes de Cooperativas de Consumo, evento destinado a la puesta al d\u00eda, concientizaci\u00f3n y marcar un necesario recambio generacional en este sector del cooperativismo, seg\u00fan se\u00f1alan sus organizadores. Cont\u00f3 con la convocatoria de la Federaci\u00f3n Uruguaya de Cooperativas de Consumo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[137,174,188],"class_list":["post-2742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uruguay","tag-ccu","tag-cooperativas-de-consumo","tag-fucc"],"_links":{"self":[{"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/posts\/2742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/comments?post=2742"}],"version-history":[{"count":2,"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/posts\/2742\/revisions"}],"predecessor-version":[{"id":2745,"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/posts\/2742\/revisions\/2745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/media\/2743"}],"wp:attachment":[{"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/media?parent=2742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/categories?post=2742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/modocooperativo.uy\/index.php\/wp-json\/wp\/v2\/tags?post=2742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}